{"id":172,"date":"2015-10-07T12:20:08","date_gmt":"2015-10-07T10:20:08","guid":{"rendered":"https:\/\/www.duschenprofis.de\/magazin\/?p=172"},"modified":"2025-11-20T11:20:15","modified_gmt":"2025-11-20T10:20:15","slug":"lichtkonzepte-fuers-bad","status":"publish","type":"post","link":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/","title":{"rendered":"Lichtkonzepte f\u00fcr Ihr Bad: Da strahlt nicht nur das Badezimmer"},"content":{"rendered":"<section  class='av_textblock_section av-mfzea7rm-6a8621e431dddea4be15e0afa7504919 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-189 aligncenter\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg\" alt=\"knalliges Badezimmer mit ungew\u00f6hnlicher Lampe\" width=\"550\" height=\"437\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg 550w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13-300x238.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/p>\n<p><strong>Wir verbringen viel Zeit im Badezimmer und nutzen es den ganzen Tag: Morgens zum Aufwachen und schnellen Stylen, abends zur Entspannung und Vorbereitung auf einen erholsamen Schlaf. Damit das Bad all diese Aufgaben erf\u00fcllen kann, braucht es zu jeder Zeit die perfekte Beleuchtung. Wir zeigen Ihnen, was Sie dabei beachten m\u00fcssen und welches Lichtkonzept Ihr Bad zum Strahlen bringt. <\/strong><!--more--><\/p>\n<h2>Lichtoase Badezimmer: Die Grundregeln<\/h2>\n<p>Mit dem richtigen Licht steht Ihnen Ihr Bad zu jeder Tageszeit zu Diensten. Bei der Planung gilt es allerdings einige Grundregeln zu beachten.<\/p>\n<h3>Sicherheit geht vor Sch\u00f6nheit<\/h3>\n<p>Im Bad trifft Feuchtigkeit auf Strom. Daher m\u00fcssen Sie sowohl bei funktionalen als auch dekorativen Lichtelementen einige Schutzma\u00dfnahmen beachten. Diese sind in der Norm DIN VDE 0100, Teil 701 festgelegt und gliedern sich auf <a href=\"https:\/\/www.baunetzwissen.de\/standardartikel\/Bad-und-Sanitaer_Strom-in-Baedern-DIN-VDE-0100-701_172848.html\">drei Schutzbereiche<\/a>.<\/p>\n<div id=\"attachment_173\" style=\"width: 1040px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-173\" class=\"wp-image-173 size-large\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du1-1030x629.jpg\" alt=\"Grundriss eines Badezimmers\" width=\"1030\" height=\"629\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du1-1030x629.jpg 1030w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du1-300x183.jpg 300w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du1-768x469.jpg 768w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du1-705x431.jpg 705w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du1.jpg 1234w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-173\" class=\"wp-caption-text\">Die Schutzanforderungen richten sich nach der Platzierung der Leuchte im Badezimmer.<\/p><\/div>\n<p>Die h\u00f6chste Schutzart IP X7 (Schutz gegen absoluten Wasserkontakt) betrifft Badewanne und Dusche: Im Bereich BO d\u00fcrfen Leuchten maximal eine Schutzkleinspannung bis AC 12 Volt erzeugen und ausdr\u00fccklich zur Installation im Wannenbereich zugelassen sein.<\/p>\n<p>Der zweite Schutzbereich B1 erstreckt sich \u00fcber einen Radius von 60 cm um den ersten Schutzbereich. Leuchten m\u00fcssen hier die Schutzart IP X5 (Strahlwasserschutz) aufweisen und d\u00fcrfen maximal eine Schutzkleinspannung bis AC 25 Volt erzeugen.<\/p>\n<p>Mit einer Duschabtrennung sind Sie damit schon auf der sicheren Seite \u2013 falls Sie noch keine haben, werden Sie sicherlich die passende <a href=\"https:\/\/www.duschenprofis.de\/duschabtrennungen.html\">Duschabtrennung in unserem Konfigurator finden.<\/a> Sind Badewanne oder Dusche allerdings nicht mit einer festen Begrenzung ausgestattet, m\u00fcssen Leuchten in einem dritten Schutzbereich B2 die Schutzart IP X4 (Schutz gegen Spritzwasser) aufweisen.<\/p>\n<p>Alle weiteren Leuchten im Raum im Bereich B3 sind frei von Schutzanforderungen gegen Wasserkontakt.<\/p>\n<h3>Die Erleuchtung \u2013 sch\u00f6n und sinnvoll<\/h3>\n<p>Licht gibt unserer inneren Uhr den Takt vor: Es steuert die K\u00f6rperfunktionen im 24-Stunden-Rhythmus und gibt uns Energie, denn das richtige Licht tr\u00e4gt zum Wohlbefinden und zur k\u00f6rperlichen Gesundheit bei.<\/p>\n<div id=\"attachment_175\" style=\"width: 859px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-175\" class=\"wp-image-175 size-full\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du2.jpg\" alt=\"modernes Badezimmer\" width=\"849\" height=\"565\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du2.jpg 849w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du2-300x200.jpg 300w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du2-768x511.jpg 768w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du2-705x469.jpg 705w\" sizes=\"auto, (max-width: 849px) 100vw, 849px\" \/><p id=\"caption-attachment-175\" class=\"wp-caption-text\">Um alle Aufgaben erf\u00fcllen zu k\u00f6nnen, muss ein Bad von allen Seiten strahlen.<\/p><\/div>\n<ul>\n<li>Helles Licht ist Voraussetzung f\u00fcr Sichtbarkeit und somit auch f\u00fcr Sicherheit<\/li>\n<li>Geeignet sind Gl\u00fch- und Halogengl\u00fchlampen, Leuchtstofflampen und LEDs. Vergleichen Sie bei der Auswahl deren Eigenschaften hinsichtlich Farbe, Lebensdauer und Umweltvertr\u00e4glichkeit.<\/li>\n<\/ul>\n<p>Daneben sollten Sie auf eine blende- und schattenfreie Spiegelbeleuchtung achten. Je nach Modell gelingt dies mithilfe von integrierten oder an beiden Seiten montierten Leuchtmitteln. \u00dcber sehr gro\u00dfen Spiegeln ist ein zus\u00e4tzlicher Strahler empfehlenswert.<\/p>\n<p>Sobald die funktionalen Aspekte gesichert sind, d\u00fcrfen Sie sich den dekorativen Zwecken widmen. Setzen Sie gl\u00e4nzende Highlights auf sch\u00f6nen Kommoden, Vitrinen oder Nischen mit Akzentleuchten. Unsere <a href=\"https:\/\/www.duschenprofis.de\/duschkabinen\/xxl-dusche.html\">XXL-Duschen<\/a> zum Beispiel eigenen sich hervorragend f\u00fcr die Platzierung seitlich strahlender Lichtleisten \u2013 in unserem Online-Shop stehen zahlreiche Modelle f\u00fcr Sie zur Wahl. Kerzen oder Leuchtmittel mit Farbwechsel sorgen f\u00fcr eine entspannte Stimmung und garantieren Ihnen erholsame Stunden im Bad.<\/p>\n<div id=\"attachment_177\" style=\"width: 576px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-177\" class=\"wp-image-177 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du3.jpg\" alt=\"beleuchteter Wasserstrahl\" width=\"566\" height=\"848\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du3.jpg 566w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du3-200x300.jpg 200w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du3-471x705.jpg 471w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><p id=\"caption-attachment-177\" class=\"wp-caption-text\">Ein leuchtender Wasserstrahl ist garantiert ein Blickfang in Ihrem Badzimmer.<\/p><\/div>\n<h2>Finden Sie das richtige Lichtkonzept: Wir zeigen Ihnen 6 Ideen f\u00fcr 6 Badezimmer-Typen<\/h2>\n<p>Welches Lichtkonzept Ihr Badezimmer ins rechte Licht r\u00fcckt, ist abh\u00e4ngig von Gr\u00f6\u00dfe und Interieur. W\u00e4hrend dunkle Farben das Licht weniger reflektieren, absorbieren Rot- und Braunt\u00f6ne beispielsweise das aktivierende Blaulicht. Ob gro\u00df oder klein, funktional oder romantisch: Wir zeigen Ihnen das passende Lichtkonzept f\u00fcr Ihr Bad.<\/p>\n<h3>Typ 1: Das Home Spa \u2013 gro\u00dfe Badezimmer ab 15 qm<\/h3>\n<p>In gro\u00dfen B\u00e4dern geht Funktionalit\u00e4t vor Design. Zun\u00e4chst gilt es daher die Grundbeleuchtung mit einer weitstrahlenden Leuchte in der Raummitte sicherzustellen. Anschlie\u00dfend k\u00f6nnen Sie den Raum mithilfe vieler kleiner Spots zum Strahlen bringen und optisch strukturieren.<\/p>\n<div id=\"attachment_178\" style=\"width: 552px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-178\" class=\"wp-image-178 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du4.jpg\" alt=\"Lichtquellen im Badezimmer\" width=\"542\" height=\"428\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du4.jpg 542w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du4-300x237.jpg 300w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/><p id=\"caption-attachment-178\" class=\"wp-caption-text\">Viele kleine Strahler verteilen das Licht auch in die hinteren Teile gro\u00dfer Badezimmer.<\/p><\/div>\n<p>Sobald Sie die funktionale Beleuchtung sichergestellt haben, k\u00f6nnen Sie sich in gro\u00dfen B\u00e4dern bei Akzent- und Stimmungslicht austoben. <em>\u201eEine abwechslungsreiche Lichtatmosph\u00e4re entsteht durch die Kombination von verschiedenartigen Lichtquellen \u2013 den Leuchten an der Decke, \u00fcber dem Spiegel und an den W\u00e4nden, ausgestattet mit direktem Spotlight, diffusem weichen Licht und indirekter Beleuchtung gegen W\u00e4nde und Decke\u201c<\/em>, erkl\u00e4rt Ulrich Beckert. Von Wohnungen bis hin zu B\u00fcrogeb\u00e4uden: Der Innenarchitekt und Lichtgestalter kennt die Tricks, um <a href=\"http:\/\/www.beckertsoancapollak.de\/projekte\/\">R\u00e4ume ins rechte Licht<\/a> zu r\u00fccken.<\/p>\n<p>Markieren Sie zum Beispiel Themenbereiche durch einen dezenten Stilmix der Leuchten: Romantische Kerzen an der Badewanne bilden einen spannenden Kontrast zu cleanen Lichtleisten in der angrenzenden <a href=\"https:\/\/www.duschenprofis.de\/duschkabinen\/\">Duschkabine<\/a>.<\/p>\n<div id=\"attachment_179\" style=\"width: 633px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-179\" class=\"wp-image-179 size-full\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du5.jpg\" alt=\"strukturiertes Badezimmer\" width=\"623\" height=\"414\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du5.jpg 623w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du5-300x199.jpg 300w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-179\" class=\"wp-caption-text\">In der Mitte eine gro\u00dfe Leuchte, am Spiegel indirekte Strahlen, im WC kleine Spots \u2013 dank der verschiedenen Lichtquellen wirkt der Raum optisch strukturiert.<\/p><\/div>\n<h3>Typ 2: Klein, aber fein \u2013 Badezimmer unter 6 m<sup>2<\/sup><\/h3>\n<p>An der Anzahl der Quadratmeter kann Licht nichts ver\u00e4ndern \u2013 an der wahrgenommenen Gr\u00f6\u00dfe schon. Ziel des Lichtkonzepts in kleinen B\u00e4dern ist somit die optische Vergr\u00f6\u00dferung. Ein kleines Bad braucht viel Licht, das m\u00f6glichst wenig des wertvollen Platzes in Anspruch nimmt.<\/p>\n<p>Bringen Sie an der Decke helle Spots an, die Sie in verschiedene Richtungen drehen. So generieren Sie ein Gef\u00fchl von Weite. Nach oben gerichtete Leuchtmittel an den W\u00e4nden schenken dem Raum optisch H\u00f6he: <em>\u201eDiffus gegen die Decke strahlende Lichtvouten heben die Decke an und der Raum wirkt gro\u00dfz\u00fcgiger\u201c<\/em>, r\u00e4t der Experte.<\/p>\n<div id=\"attachment_180\" style=\"width: 552px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-180\" class=\"wp-image-180 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du6.jpg\" alt=\"wei\u00dfes Badezimmer im Romantik-Look\" width=\"542\" height=\"428\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du6.jpg 542w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du6-300x237.jpg 300w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/><p id=\"caption-attachment-180\" class=\"wp-caption-text\">Nach oben gerichtete Leuchten geben dem Raum H\u00f6he: Perfekt f\u00fcr die optische Vergr\u00f6\u00dferung.<\/p><\/div>\n<p>Auch indirektes Licht l\u00e4sst B\u00e4der gro\u00df rauskommen. Doch achten Sie auch hierbei auf den funktionalen Aspekt. F\u00fcr rein dekorative Accessoires ist in Minib\u00e4dern der Platz zu schade.<\/p>\n<p>Nutzen Sie in kleinen B\u00e4dern die Effekte von Reflexen und Spiegelungen, die die Leuchtkraft einer Lichtquelle verdoppeln. Helle Farben eigenen sich hierf\u00fcr am besten. Neben hartem Wei\u00df lockern auch unreine Wei\u00dft\u00f6ne wie Perlmutt die Gr\u00f6\u00dfenbegrenzung optisch auf.<\/p>\n<div id=\"attachment_181\" style=\"width: 633px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-181\" class=\"wp-image-181 size-full\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du7.jpg\" alt=\"Bad mit Holzelementen\" width=\"623\" height=\"414\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du7.jpg 623w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du7-300x199.jpg 300w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><p id=\"caption-attachment-181\" class=\"wp-caption-text\">Reflektiert im Spiegel strahlt eine Lichtquelle gleich doppelt so hell.<\/p><\/div>\n<h3>Typ 3: Das Minimalistische<\/h3>\n<p>Licht dient zum Sehen: Z\u00e4hlen Sie eher zum minimalistischen Badtyp, muss Ihr Licht vor allem eines k\u00f6nnen: leuchten! Ob es eine angenehme Stimmung erzeugt oder Ihnen bei der Strukturierung Ihres Tagesablaufes hilft, interessiert Sie nicht. Ihr Lichtkonzept folgt in diesem Fall dem Grundsatz \u201eweniger ist mehr\u201c.<\/p>\n<p>In cleane Badezimmer f\u00fcgen sich zur\u00fcckhaltende Leuchten aus Chrom oder Alu mit silbernem oder schwarzem Finish im Industrial Chic elegant ein. Passend dazu schaffen <em>\u201eLeuchten mit geometrischen Formen, ein hinterleuchteter Spiegel oder die Beleuchtung einer ganzen Wand oder Decke eine sachliche und die Architektursprache unterst\u00fctzende Ausstrahlung\u201c<\/em>, wei\u00df der Experte.<\/p>\n<div id=\"attachment_182\" style=\"width: 1040px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-182\" class=\"wp-image-182 size-large\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du8-1030x530.jpg\" alt=\"l\u00e4ngliches, minimalistisches Badezimmer\" width=\"1030\" height=\"530\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du8-1030x530.jpg 1030w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du8-300x154.jpg 300w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du8-768x395.jpg 768w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du8-705x363.jpg 705w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du8.jpg 1359w\" sizes=\"auto, (max-width: 1030px) 100vw, 1030px\" \/><p id=\"caption-attachment-182\" class=\"wp-caption-text\">Qualit\u00e4t statt Quantit\u00e4t: Ein paar weit strahlende Leuchten f\u00fcllen den gesamten Raum mit Licht ohne sich aufzudr\u00e4ngen.<\/p><\/div>\n<p>Erg\u00e4nzen Sie die Grundbeleuchtung um wenige, aber daf\u00fcr klare Akzente durch indirektes Licht, zum Beispiel hinter dem Spiegel, oder helle Strahler. Dieses Licht strukturiert den Raum und bleibt selbst optisch im Hintergrund.<\/p>\n<div id=\"attachment_183\" style=\"width: 853px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-183\" class=\"wp-image-183 size-full\" src=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du9.jpg\" alt=\"minimalistisches Badezimmer in schwarz\" width=\"843\" height=\"569\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du9.jpg 843w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du9-300x202.jpg 300w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du9-768x518.jpg 768w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du9-705x476.jpg 705w\" sizes=\"auto, (max-width: 843px) 100vw, 843px\" \/><p id=\"caption-attachment-183\" class=\"wp-caption-text\">Kleine Akzente mit gro\u00dfer Wirkung: Sie bringen Ordnung in Ihr Badezimmer.<\/p><\/div>\n<h3>Typ 4: Das Romantische<\/h3>\n<p>Ein romantisches Interieur ist das Gegenst\u00fcck zum minimalistischen Typ. Licht dient vor allem der Stimmung und Leuchten der Dekoration.<\/p>\n<p>Verzichten Sie daher auf harte Akzente. Eine funktionale Strukturierung braucht Ihre Nasszelle nicht. Diese freut sich viel mehr \u00fcber helle Stimmungsleuchten in warmwei\u00dfem Licht, dass durch Kristallglas in wilde Strahlen gebrochen und in den ganzen Raum reflektiert wird. Besonders sch\u00f6n gelingt dieser Effekt mit k\u00f6niglichen Kronleuchtern.<\/p>\n<div id=\"attachment_186\" style=\"width: 552px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-186\" class=\"wp-image-186 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du10.jpg\" alt=\"royales Badezimmer\" width=\"542\" height=\"428\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du10.jpg 542w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du10-300x237.jpg 300w\" sizes=\"auto, (max-width: 542px) 100vw, 542px\" \/><p id=\"caption-attachment-186\" class=\"wp-caption-text\">Ein Kronleuchter verwandelt Ihr Bad in ein k\u00f6nigliches Spa \u2013 Entspannung pur!<\/p><\/div>\n<p>Helle Leuchten in Beige- und Wei\u00dft\u00f6nen, erg\u00e4nzt von gl\u00e4nzenden Highlights in Gold und Silber bilden ein stilvolles Pendant zu Wandgestaltungen und M\u00f6beln im Vintage-Stil. Im Materialmix aus Textilen, Holz und Metallen erzeugen sie eine vertr\u00e4umte und ungezwungene Atmosph\u00e4re.<\/p>\n<p>Im romantischen Bad ist weniger mehr, erkl\u00e4rt der Lichtgestalter: <em>\u201eIm Bad entsteht stimmungsvolles Licht durch wenig Licht, das charmante Details, wie ein besonderes Accessoire oder ein Tischchen beleuchtet. Das erzeugt eine besondere und aufgeladene Atmosph\u00e4re. Hierf\u00fcr eignet sich eine Schirm-Pendelleuchte, die Licht gerichtet abgibt. Auch Duftkerzen in Wandnischen setzen sinnliche Akzente.\u201c<\/em><\/p>\n<div id=\"attachment_187\" style=\"width: 556px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-187\" class=\"wp-image-187 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du11.jpg\" alt=\"romantisches Badezimmer mit Musterelementen\" width=\"546\" height=\"434\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du11.jpg 546w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du11-300x238.jpg 300w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><p id=\"caption-attachment-187\" class=\"wp-caption-text\">In verspielten Interieurs d\u00fcrfen die Leuchten weder zu aufdringlich, noch zu dezent sein: Ein Materialmix und zarte T\u00f6ne erf\u00fcllt diesen Zweck.<\/p><\/div>\n<h3>Typ 5: Das Glamour\u00f6se<\/h3>\n<p>In Ihrem luxuri\u00f6sen Badezimmer geben Glamour und Style den Ton an. Das Licht muss hell sein, ja \u2013 viel wichtiger ist jedoch, dass es Ihre Luxusaccessoires wie Stylingprodukte und Dekoartikel perfekt in Szene setzt.<\/p>\n<div id=\"attachment_188\" style=\"width: 556px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-188\" class=\"wp-image-188 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du12.jpg\" alt=\"futuristisches Badezimmer\" width=\"546\" height=\"433\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du12.jpg 546w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du12-300x238.jpg 300w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><p id=\"caption-attachment-188\" class=\"wp-caption-text\">Eine breit strahlende Lampe erzeugt luxuri\u00f6se Reflexe und r\u00fcckt die wichtigsten Bereiche in der Vordergrund.<\/p><\/div>\n<p>Montieren Sie am h\u00f6chsten Punkt der Decke eine pomp\u00f6se Leuchte. Egal ob Kronleuchter oder klassischer Strahler: Hauptsache, die Lampe erf\u00fcllt den gesamten Raum mit Licht, das auf Ihren M\u00f6beln reflektiert wird. Wie Sie diesen Effekt erzeugen, wei\u00df Ulrich Beckert: <em>\u201eLeuchten aus klarem Glas verdecken das Licht der Lichtquelle nicht. Das Licht strahlt so auf die umliegenden Materialien und Oberfl\u00e4chen, die es zu illuminieren gilt. Glitzert das Material, entstehen kraftvolle und anregende Stimmungen.\u201c<\/em><\/p>\n<p><a href=\"https:\/\/www.duschenprofis.de\/magazin\/badezimmer-neu-gestalten\/\">Parfumflakons, Badezubeh\u00f6r, Make-Up-Palette<\/a>: Dekorative Pflege- und Stylingprodukte setzen indirekt beleuchtete Ablagen in Szene. Die warmen Lichtreflexe dienen als repr\u00e4sentative B\u00fchne f\u00fcr Ihre liebsten Sch\u00f6nheitshelfer und gleichzeitig als Stimmungsleuchte f\u00fcr eine entspannte Atmosph\u00e4re in Ihrem Badezimmer.<\/p>\n<h3>Typ 6: Das Stylische<\/h3>\n<p>Shabby Chic, Industrial, Boho: Sie kennen die Interieurtrends. Bei der Auswahl Ihrer Lichtquellen orientieren Sie sich an deren Designfaktor und eine gew\u00f6hnliche Lampe ist f\u00fcr Sie als Grundbeleuchtung undenkbar? Dann brauchen Sie Lampen mit Potential zum Eye Catcher \u2013 ob funktional oder nicht.<\/p>\n<div id=\"attachment_189\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-189\" class=\"wp-image-189 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg\" alt=\"knalliges Badezimmer mit modernen Lichtkonzepten\" width=\"550\" height=\"437\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg 550w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13-300x238.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><p id=\"caption-attachment-189\" class=\"wp-caption-text\">Knallige Farben und markante Lampen: Das bringt die Augen von Designfans zum Strahlen.<\/p><\/div>\n<p>Wer braucht schon langweilige Kerzen? Nutzen Sie knallige Farben als Stimmungsmacher! Rot und Gelb sind Gute-Laune-Lieferanten: Sie bringen Sie auf Hochtouren und verbessern Ihr Wohlbefinden. Gr\u00fcn und Blau helfen bei der Entspannung. Sie f\u00fchlen sich damit ausgeglichen und erholt.<\/p>\n<p>Zeigen Sie Ihr Trendgesp\u00fcr mit freigelegten Gl\u00fchlampen und Kabeln. Kunstvoll drapiert oder locker h\u00e4ngend erinnert Ihr Badezimmer damit an ein stylisches Designerloft.<\/p>\n<div id=\"attachment_190\" style=\"width: 556px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-190\" class=\"wp-image-190 size-full\" src=\"\/magazin\/wp-content\/uploads\/2015\/10\/du14.jpg\" alt=\"Badezimmer mit Weidenkranz\" width=\"546\" height=\"434\" srcset=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du14.jpg 546w, https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du14-300x238.jpg 300w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><p id=\"caption-attachment-190\" class=\"wp-caption-text\">Gl\u00fchbirnen und Kabel sind viel zu schade, um von gew\u00f6hnlichen Lampenschirmen verdeckt zu werden.<\/p><\/div>\n<p><strong>Welcher Badezimmertyp sind Sie? Nehmen Sie Ihr Interieur unter die Lupe und bringen Sie Ihre Nasszelle mit dem passenden Lichtkonzept zum Strahlen. <\/strong><\/p>\n<p><small>Bilder: Bild 1: \u00a9 Biezl\/ Wikipedia Commons, Bild 2: \u00a9 iStock \/ KatarzynaBialasiewicz, Bild 3: \u00a9 iStock \/ Baloncici, Bild 4: \u00a9 Houzz \/ Leicht USA, Bild 5: \u00a9 iStock \/ ExcellentPhoto, Bild 6: \u00a9 Houzz \/ HB Dallas, Versatile Imaging, Bild 7: \u00a9 iStock \/ Jacek_kadai, Bild 8: \u00a9 Houzz \/ Stefan M\u00f6bel, Bild 9: \u00a9 iStock \/ Photo_HamsterMan, Bild 10: \u00a9 Houzz \/ Preferred Kitchen &amp; Bath, Bild 11: \u00a9 Houzz \/ Kohler, Bild 12: \u00a9 Houzz \/ Y &amp; S architecture-interior design, Bild 13: (c) Houzz \/ Overmyer Architects, Bild 14: \u00a9 Houzz \/ MARTIN architects<\/small><\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Wir verbringen viel Zeit im Bad: Morgens zum Aufwachen und schnellen Stylen, abends zur Entspannung und Vorbereitung auf einen erholsamen Schlaf. Wir zeigen Ihnen die perfekte Beleuchtung zu jeder Tageszeit!<\/p>\n","protected":false},"author":2,"featured_media":189,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,8],"tags":[13,16],"class_list":["post-172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-heimwerken","category-tipps-und-tricks","tag-baderneuerung","tag-beleuchtung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Badbeleuchtung: Lichtkonzepte f\u00fcr Ihr Badezimmer<\/title>\n<meta name=\"description\" content=\"Unsere Tipps f\u00fcr Licht und Leuchten helfen Ihnen bei Ihrer Badezimmer-Beleuchtung \u2013 damit geht nicht nur im Bad ein Licht auf!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Badbeleuchtung: Lichtkonzepte f\u00fcr Ihr Badezimmer\" \/>\n<meta property=\"og:description\" content=\"Unsere Tipps f\u00fcr Licht und Leuchten helfen Ihnen bei Ihrer Badezimmer-Beleuchtung \u2013 damit geht nicht nur im Bad ein Licht auf!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/\" \/>\n<meta property=\"og:site_name\" content=\"Duschenprofis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/duschenprofis\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-07T10:20:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-20T10:20:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Duschenprofis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Duschenprofis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/\"},\"author\":{\"name\":\"Duschenprofis\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/#\\\/schema\\\/person\\\/5e10dfd59a799b37675a368453bf2ae8\"},\"headline\":\"Lichtkonzepte f\u00fcr Ihr Bad: Da strahlt nicht nur das Badezimmer\",\"datePublished\":\"2015-10-07T10:20:08+00:00\",\"dateModified\":\"2025-11-20T10:20:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/\"},\"wordCount\":1927,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/du13.jpg\",\"keywords\":[\"Baderneuerung\",\"Beleuchtung\"],\"articleSection\":[\"Heimwerken\",\"Tipps &amp; Tricks\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/\",\"url\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/\",\"name\":\"Badbeleuchtung: Lichtkonzepte f\u00fcr Ihr Badezimmer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/du13.jpg\",\"datePublished\":\"2015-10-07T10:20:08+00:00\",\"dateModified\":\"2025-11-20T10:20:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/#\\\/schema\\\/person\\\/5e10dfd59a799b37675a368453bf2ae8\"},\"description\":\"Unsere Tipps f\u00fcr Licht und Leuchten helfen Ihnen bei Ihrer Badezimmer-Beleuchtung \u2013 damit geht nicht nur im Bad ein Licht auf!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/du13.jpg\",\"contentUrl\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/du13.jpg\",\"width\":550,\"height\":437,\"caption\":\"knalliges Badezimmer mit ungew\u00f6hnlicher Lampe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/lichtkonzepte-fuers-bad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lichtkonzepte f\u00fcr Ihr Bad: Da strahlt nicht nur das Badezimmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/\",\"name\":\"Duschenprofis\",\"description\":\"Neues von den Duschenprofis: Tipps und Tricks rund ums Bad, DiY und Ratgeber zur Badplanung.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.duschenprofis.de\\\/magazin\\\/#\\\/schema\\\/person\\\/5e10dfd59a799b37675a368453bf2ae8\",\"name\":\"Duschenprofis\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Badbeleuchtung: Lichtkonzepte f\u00fcr Ihr Badezimmer","description":"Unsere Tipps f\u00fcr Licht und Leuchten helfen Ihnen bei Ihrer Badezimmer-Beleuchtung \u2013 damit geht nicht nur im Bad ein Licht auf!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/","og_locale":"de_DE","og_type":"article","og_title":"Badbeleuchtung: Lichtkonzepte f\u00fcr Ihr Badezimmer","og_description":"Unsere Tipps f\u00fcr Licht und Leuchten helfen Ihnen bei Ihrer Badezimmer-Beleuchtung \u2013 damit geht nicht nur im Bad ein Licht auf!","og_url":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/","og_site_name":"Duschenprofis","article_publisher":"https:\/\/www.facebook.com\/duschenprofis\/","article_published_time":"2015-10-07T10:20:08+00:00","article_modified_time":"2025-11-20T10:20:15+00:00","og_image":[{"width":550,"height":437,"url":"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg","type":"image\/jpeg"}],"author":"Duschenprofis","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Duschenprofis","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#article","isPartOf":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/"},"author":{"name":"Duschenprofis","@id":"https:\/\/www.duschenprofis.de\/magazin\/#\/schema\/person\/5e10dfd59a799b37675a368453bf2ae8"},"headline":"Lichtkonzepte f\u00fcr Ihr Bad: Da strahlt nicht nur das Badezimmer","datePublished":"2015-10-07T10:20:08+00:00","dateModified":"2025-11-20T10:20:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/"},"wordCount":1927,"commentCount":1,"image":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg","keywords":["Baderneuerung","Beleuchtung"],"articleSection":["Heimwerken","Tipps &amp; Tricks"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/","url":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/","name":"Badbeleuchtung: Lichtkonzepte f\u00fcr Ihr Badezimmer","isPartOf":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#primaryimage"},"image":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg","datePublished":"2015-10-07T10:20:08+00:00","dateModified":"2025-11-20T10:20:15+00:00","author":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/#\/schema\/person\/5e10dfd59a799b37675a368453bf2ae8"},"description":"Unsere Tipps f\u00fcr Licht und Leuchten helfen Ihnen bei Ihrer Badezimmer-Beleuchtung \u2013 damit geht nicht nur im Bad ein Licht auf!","breadcrumb":{"@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#primaryimage","url":"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg","contentUrl":"https:\/\/www.duschenprofis.de\/magazin\/wp-content\/uploads\/2015\/10\/du13.jpg","width":550,"height":437,"caption":"knalliges Badezimmer mit ungew\u00f6hnlicher Lampe"},{"@type":"BreadcrumbList","@id":"https:\/\/www.duschenprofis.de\/magazin\/lichtkonzepte-fuers-bad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.duschenprofis.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Lichtkonzepte f\u00fcr Ihr Bad: Da strahlt nicht nur das Badezimmer"}]},{"@type":"WebSite","@id":"https:\/\/www.duschenprofis.de\/magazin\/#website","url":"https:\/\/www.duschenprofis.de\/magazin\/","name":"Duschenprofis","description":"Neues von den Duschenprofis: Tipps und Tricks rund ums Bad, DiY und Ratgeber zur Badplanung.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.duschenprofis.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.duschenprofis.de\/magazin\/#\/schema\/person\/5e10dfd59a799b37675a368453bf2ae8","name":"Duschenprofis"}]}},"lang":"de","translations":{"de":172,"de-at":7837},"pll_sync_post":{"de":true},"_links":{"self":[{"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":8,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"predecessor-version":[{"id":8513,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/posts\/172\/revisions\/8513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/media\/189"}],"wp:attachment":[{"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.duschenprofis.de\/magazin\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}